{"id":1385,"date":"2020-10-18T21:56:34","date_gmt":"2020-10-18T19:56:34","guid":{"rendered":"http:\/\/ycm-berlin.de\/blog\/?p=1385"},"modified":"2020-10-19T10:21:54","modified_gmt":"2020-10-19T08:21:54","slug":"1-training-am-22-05-2020","status":"publish","type":"post","link":"https:\/\/ycm-berlin.de\/blog\/1-training-am-22-05-2020\/","title":{"rendered":"1. Training am 22.05.2020"},"content":{"rendered":"\n<p>Endlich! Endlich ist es soweit: Wir d\u00fcrfen wieder trainieren. Die offizielle Verk\u00fcndung durch den Landessportbund und unserem Vereinsvorsitzenden war wirklich eine Erleichterung. <\/p>\n\n\n<p><!--more--><\/p>\n\n\n<p>Das war ein Start in die Saison 2020, oder? Wer h\u00e4tte das gedacht? In den Winterferien h\u00e4tten wir noch nicht daran geglaubt, dass sich der Start der Segelsaison und damit auch das Jugendsegeln so verz\u00f6gern w\u00fcrde. Waren wir doch erst Anfang M\u00e4rz gemeinsam in der Ninja Hall gewesen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"472\" height=\"1024\" src=\"http:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-1-472x1024.jpeg\" alt=\"\" class=\"wp-image-1515\" srcset=\"https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-1-472x1024.jpeg 472w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-1-138x300.jpeg 138w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-1-708x1536.jpeg 708w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-1.jpeg 738w\" sizes=\"(max-width: 472px) 100vw, 472px\" \/><figcaption>Ben, Pepe, Lara und Anna beim Waldspaziergang.<br>Foto: Inge Neumerkel<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"472\" height=\"1024\" src=\"http:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-3-472x1024.jpeg\" alt=\"\" class=\"wp-image-1517\" srcset=\"https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-3-472x1024.jpeg 472w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-3-138x300.jpeg 138w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-3-708x1536.jpeg 708w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-3.jpeg 738w\" sizes=\"(max-width: 472px) 100vw, 472px\" \/><figcaption>In der Lieper Bucht sind die Schw\u00e4ne immer zahlreich vertreten.<br>Foto: Inge Neumerkel<\/figcaption><\/figure>\n\n\n\n<p>W\u00e4hrend des COVID-19-Lockdown waren einige Familien regelm\u00e4\u00dfig im Grunewald spazieren und haben die Insel Lindwerder vom Aussichtspunkt betrachtet. Uns war ganz wehm\u00fctig ums Herz und umso gr\u00f6\u00dfer war die Freude, als wir endlich wieder das Vereinsgel\u00e4nde betreten durften. Zun\u00e4chst war es jedoch nur gestattet die Boote zu slippen &#8211; Training war noch nicht erlaubt. Nur z\u00f6gerlich und unter strenger Beachtung der Hygienema\u00dfnahmen wurde der Verein von Woche zu Woche ge\u00f6ffnet. Die Familien waren dar\u00fcber sehr froh, dass sie wieder auf ihre Boote durften, denn ein Tapetenwechsel war nach fast sechs Wochen wirklich n\u00f6tig!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"472\" src=\"http:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-2-1024x472.jpeg\" alt=\"\" class=\"wp-image-1518\" srcset=\"https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-2-1024x472.jpeg 1024w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-2-300x138.jpeg 300w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-2-768x354.jpeg 768w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-2-1536x708.jpeg 1536w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/Waldspaziergang-2.jpeg 1600w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption>Blick auf die Insel Lindwerder. <br>Foto: Inge Neumerkel<\/figcaption><\/figure>\n\n\n\n<p>Am Freitag, den 22.05.2020, durfte das erste Jugendtraining in diesem Jahr stattfinden &#8211; seitdem wieder regelm\u00e4\u00dfig jedes Wochenende. Aufgrund der Hygienema\u00dfnahmen wurden die Segler*innen zun\u00e4chst in zwei Gruppen von je acht Personen inkl. einer Trainerin aufgeteilt. Es durften au\u00dferdem nur Geschwister gemeinsam im Teeny segeln, alle anderen sa\u00dfen allein in einem Opti.  Die Kinder, welche sonst Vorschoter im Teeny waren, fanden es richtig gut mal selbst an der Pinne zu sitzen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"576\" src=\"http:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/erstes-Training-2020-1024x576.jpeg\" alt=\"\" class=\"wp-image-1461\" srcset=\"https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/erstes-Training-2020-1024x576.jpeg 1024w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/erstes-Training-2020-300x169.jpeg 300w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/erstes-Training-2020-768x432.jpeg 768w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/erstes-Training-2020-1536x864.jpeg 1536w, https:\/\/ycm-berlin.de\/blog\/wp-content\/uploads\/2020\/10\/erstes-Training-2020.jpeg 1600w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption>Das erste Training 2020 &#8211; unter den strengen Hygienema\u00dfnahmen aufgrund Corona. <br>Foto: Inge Neumerkel<\/figcaption><\/figure>\n\n\n\n<p>Die besonderen Trainingsumst\u00e4nde hielten bis zu den Sommerferien an. Danach durfte das Training in den gewohnten Gruppen sowie in den gewohnten Teeny-Teams stattfinden &#8211; nat\u00fcrlich weiterhin unter Beachtung der aktuell geltenden Hygienema\u00dfnahmen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Endlich! Endlich ist es soweit: Wir d\u00fcrfen wieder trainieren. Die offizielle Verk\u00fcndung durch den Landessportbund und unserem Vereinsvorsitzenden war wirklich eine Erleichterung.<\/p>\n","protected":false},"author":2,"featured_media":1461,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,44],"tags":[36,63,35,39,34],"_links":{"self":[{"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/posts\/1385"}],"collection":[{"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/comments?post=1385"}],"version-history":[{"count":5,"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/posts\/1385\/revisions"}],"predecessor-version":[{"id":1519,"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/posts\/1385\/revisions\/1519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/media\/1461"}],"wp:attachment":[{"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/media?parent=1385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/categories?post=1385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/tags?post=1385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}