{"id":1157,"date":"2020-10-12T20:15:20","date_gmt":"2020-10-12T18:15:20","guid":{"rendered":"http:\/\/ycm-berlin.de\/blog\/?page_id=1157"},"modified":"2020-11-27T19:25:26","modified_gmt":"2020-11-27T18:25:26","slug":"2019-2","status":"publish","type":"page","link":"https:\/\/ycm-berlin.de\/blog\/archiv-teeny\/2019-2\/","title":{"rendered":"2019"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":1147,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/pages\/1157"}],"collection":[{"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/comments?post=1157"}],"version-history":[{"count":10,"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/pages\/1157\/revisions"}],"predecessor-version":[{"id":1636,"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/pages\/1157\/revisions\/1636"}],"up":[{"embeddable":true,"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/pages\/1147"}],"wp:attachment":[{"href":"https:\/\/ycm-berlin.de\/blog\/wp-json\/wp\/v2\/media?parent=1157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}